{"id":7806,"date":"2021-06-17T06:47:01","date_gmt":"2021-06-17T05:47:01","guid":{"rendered":"https:\/\/see-the-big-picture.com\/?page_id=7806"},"modified":"2021-06-17T06:47:02","modified_gmt":"2021-06-17T05:47:02","slug":"teilnehmen","status":"publish","type":"page","link":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/","title":{"rendered":"Teilnehmen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7806\" class=\"elementor elementor-7806 elementor-5071\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6135dd7b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6135dd7b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ce1338f\" data-id=\"7ce1338f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-569a3279 elementor-widget elementor-widget-heading\" data-id=\"569a3279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Teilnehmen<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1320ea3e elementor-widget elementor-widget-heading\" data-id=\"1320ea3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Teile Deine Vision f\u00fcr eine gr\u00f6\u00dfere Perspektive<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13961f97 elementor-widget elementor-widget-text-editor\" data-id=\"13961f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>See the Big Picture ist ein kollaboratives Kunstprojekt. Hier stehen Hobbykunstschaffende und professionelle K\u00fcnstlerinnen und K\u00fcnstler Seite an Seite, um mit ihrer Kunst eine Botschaft f\u00fcr mehr Zusammenhalt in der Welt zu verbreiten. Jeder individuelle Beitrag hat seine eigene Bedeutung und Aussage, im Vordergrund steht allerdings das Gesamtkunstwerk: the Big Picture.<\/p>\n<p>Bist Du Maler*in oder Fotograf*in und w\u00fcrdest Du gerne ein Teil von StBP werden? Gro\u00dfartig! Bevor wir \u00fcber Deine Teilnahme sprechen, solltest Du Dich bereits mit den wichtigsten Details vertraut machen. Auf dieser Seite findest Du daher einen \u00dcberblick \u00fcber diverse Einzelheiten, \u00fcber die Du Bescheid wissen solltest \u2013 inklusive Erkl\u00e4rvideo und FAQ. Sind dann noch Fragen offen oder bist Du vielleicht schon so weit, bei See the Big Picture mitzumachen, nimm bitte einfach Kontakt mit uns auf.<\/p>\n<p>Wir freuen uns schon jetzt, von Dir zu h\u00f6ren.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-719028b6\" data-id=\"719028b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-761559d5 elementor-widget elementor-widget-toggle\" data-id=\"761559d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1981\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1981\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">So wirst Du Teil von See the Big Picture<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1981\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1981\"><ol>\n<li><em>Kontakt aufnehmen<\/em>: Sag uns, wer Du bist und dass Du mitmachen m\u00f6chtest<\/li>\n<li><em>Kreativ werden<\/em>: Male ein Bild oder mache ein Foto f\u00fcr das Projekt<\/li>\n<li><em>Paket versenden<\/em>: Schicke uns das fertige Kunstwerk \u2013 auf eigene Kosten<\/li>\n<\/ol>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1982\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1982\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mitglied des Projektes sein<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1982\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1982\"><ul>\n<li>Wir pr\u00e4sentieren Dich und Dein Bild auf unserer Website (<a href=\"http:\/\/www.see-the-big-picture.com\">www-see-the-big-picture.com\/community<\/a>). Welche Informationen wir dazu von Dir brauchen, findest Du bei den FAQ.<\/li>\n<\/ul>\n<ul>\n<li>Die Initiative veranstaltet regelm\u00e4\u00dfig Ausstellungen. Bei diesen Anl\u00e4ssen werden zwar nicht immer alle Beitr\u00e4ge gleichzeitig gezeigt, dennoch werden wir daf\u00fcr sorgen, dass auch Dein Bild hin und wieder in der \u00d6ffentlichkeit zu sehen sein wird.<\/li>\n<\/ul>\n<ul>\n<li>See the Big Picture ermutigt die teilnehmenden Kunstschaffenden, sich auszutauschen und auch Neuigkeiten mit den Freundinnen und Freunden des Projektes zu teilen. Hierf\u00fcr werden verschiedene M\u00f6glichkeiten angeboten, die es der Community erm\u00f6glichen sollen, miteinander in Verbindung zu bleiben.<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44faaa4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44faaa4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83a9c6d\" data-id=\"83a9c6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f98243 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5f98243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-border-style\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63b0a7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63b0a7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ca0a89e\" data-id=\"ca0a89e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78398c2 elementor-widget elementor-widget-heading\" data-id=\"78398c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><h3><strong>Abmessungen des Bildes oder Fotos<\/strong><\/h3><\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90dbeeb elementor-widget elementor-widget-text-editor\" data-id=\"90dbeeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\n<p><em>Alle eingereichten Kunstwerke <u>M\u00dcSSEN<\/u> den unten genannten Ma\u00dfen entsprechen, damit sie in das Projekt aufgenommen werden k\u00f6nnen.<\/em><\/p>\n<ul>\n<li>Leinwandgr\u00f6\u00dfe: 100 cm (B) x 80 cm (H)<\/li>\n<li>Die obere linke Ecke und die rechte untere Ecke des Bildes m\u00fcssen freigelassen werden, jeweils 30 cm (B) x 40 cm (H)<\/li>\n<\/ul>\n<p>Erkl\u00e4rung: Jedes Kunstwerk muss diese speziellen Ma\u00dfe aufweisen, da die Bilder bei Ausstellungen in Form eines Panoramas gezeigt werden, d.h. sie werden als ein fortlaufendes Bild pr\u00e4sentiert, das das Big Picture darstellt. Die Ecken m\u00fcssen freigelassen werden, damit ein gestalterischer \u00dcbergang zwischen den einzelnen Bildern geschaffen werden kann. Nachdem StBP die Bilder erhalten hat, k\u00fcmmern sich erfahrene K\u00fcnstlerInnen darum, diese Fl\u00e4chen miteinander zu verbinden. Mit ihrer Teilnahme stimmen die Kunstschaffenden diesem Vorgehen zu.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f1bb6e\" data-id=\"5f1bb6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecf3f66 elementor-widget elementor-widget-image\" data-id=\"ecf3f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"771\" height=\"883\" src=\"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/2018\/08\/painting-dimension-new-1.jpg\" class=\"attachment-large size-large wp-image-3570\" alt=\"\" srcset=\"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/2018\/08\/painting-dimension-new-1.jpg 771w, https:\/\/see-the-big-picture.com\/wp-content\/uploads\/2018\/08\/painting-dimension-new-1-262x300.jpg 262w, https:\/\/see-the-big-picture.com\/wp-content\/uploads\/2018\/08\/painting-dimension-new-1-768x880.jpg 768w\" sizes=\"(max-width: 771px) 100vw, 771px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbc1b3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbc1b3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70d1564\" data-id=\"70d1564\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03ea181 elementor-widget elementor-widget-spacer\" data-id=\"03ea181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-053390d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"053390d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ffc95d\" data-id=\"0ffc95d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b08745 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7b08745\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-image\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04178ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04178ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff4eb00\" data-id=\"ff4eb00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7b95f1 elementor-widget elementor-widget-heading\" data-id=\"b7b95f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong><h3><strong>Thema des Bildes oder Fotos<\/strong><\/h3><\/strong><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ec87a0 elementor-widget elementor-widget-text-editor\" data-id=\"6ec87a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>StBP vereint individuelle Blickpunkte mit einer globalen Sichtweise. Der Initiative ist es daher wichtig, Raum f\u00fcr menschliche und k\u00fcnstlerische Vielfalt zu bieten. Verschiedene Sichtweisen und Meinungen sind ausdr\u00fccklich erw\u00fcnscht. Dennoch k\u00f6nnen bestimmte Inhalte nicht akzeptiert werden, wenn diese unvereinbar mit den Werten des Projekts sind. Dazu z\u00e4hlen pornografische Inhalte und Inhalte, die einer politischen, religi\u00f6sen oder kommerziellen Agenda folgen. Davon abgesehen gilt f\u00fcr die Teilnahme freie Motivwahl.<\/p>\n<p>In K\u00fcrze l\u00e4sst sich Dein Auftrag so beschreiben: Male oder fotografiere etwas, das den Mikrokosmos Deiner eigenen Lebenswelt (also z.B. Erfahrungen, Sinneswahrnehmungen, Ideen und Gedanken) mit dem Makrokosmos eines gr\u00f6\u00dferen Zusammenhangs, d.h. vor allem der Welt, verbindet.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6d453e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6d453e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-175d5ed\" data-id=\"175d5ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc72d8 elementor-widget elementor-widget-spacer\" data-id=\"2cc72d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6031f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6031f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28c44ea\" data-id=\"28c44ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-133b801 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"133b801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-lightbulb\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fc22876 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fc22876\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4076bc7b\" data-id=\"4076bc7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8001462 elementor-widget elementor-widget-heading\" data-id=\"8001462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-408d4c6 elementor-widget elementor-widget-heading\" data-id=\"408d4c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Am h\u00e4ufigsten gestellte Fragen<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f75f23 elementor-widget elementor-widget-toggle\" data-id=\"68f75f23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1761\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1761\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann wirklich jede*r an \u201eSee the Big Picture\u201c teilnehmen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1761\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1761\"><p>Grunds\u00e4tzlich ja. Uns ist es wichtig, allen hierzu die M\u00f6glichkeit zu bieten. Daher betonen wir ausdr\u00fccklich, dass sowohl Profis als auch Hobbykunstschaffende mitmachen k\u00f6nnen. Letztendlich wird f\u00fcr jedes Bild separat gepr\u00fcft, ob es zum Projekt passt.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ba0aaa elementor-widget elementor-widget-toggle\" data-id=\"31ba0aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8341\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8341\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist die Teilnahme an \u201eSee the Big Picture\u201c kostenlos?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8341\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8341\"><p>Die Teilnahme selbst ist kostenlos. Weitere Kosten, die entstehen, wie z.B. f\u00fcr den Versand, werden von den K\u00fcnstlerinnen und K\u00fcnstlern selbst getragen. Nur in Ausnahmef\u00e4llen (z.B. finanzielle Notlage) k\u00f6nnen diese Kosten \u00fcbernommen werden. In diesem Fall ist eine vorherige R\u00fccksprache mit den Verantwortlichen notwendig.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-729c5ea1 elementor-widget elementor-widget-toggle\" data-id=\"729c5ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1921\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1921\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Werde ich f\u00fcr die Teilnahme an \u201eSee the Big Picture\u201c bezahlt?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1921\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1921\"><p>Nein. Es gibt weder ein Honorar f\u00fcr die Arbeit noch eine Bezahlung f\u00fcr das Bild.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d91f21 elementor-widget elementor-widget-toggle\" data-id=\"9d91f21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist \u201eSee the Big Picture\u201d eine Galerie, bei der ich ausstellen und meine Bilder verkaufen kann?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1651\"><p>Nein. \u201eSee the Big Picture\u201c widmet sich ausschlie\u00dflich den eigenen Projektzielen. Ausstellungst\u00e4tigkeiten au\u00dferhalb der Initiative und Verk\u00e4ufe von Bildern finden nicht statt.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95458eb elementor-widget elementor-widget-toggle\" data-id=\"95458eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">In welchem Besitzverh\u00e4ltnis befindet sich mein Bild, nachdem ich es \u201eSee the Big Picture\u201c \u00fcbergebe?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1561\"><p>Mit dem Unterschreiben der Teilnahmebedingungen \u00fcbergibst Du \u201eSee the Big Picture\u201c das Bild \u2013 ohne die M\u00f6glichkeit auf Widerruf \u2013 als Dauerleihgabe. Das Bild bleibt allerdings weiterhin Dein alleiniger Besitz. Das Bild bleibt zu jeder Zeit unverk\u00e4uflich.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f84ed77 elementor-widget elementor-widget-toggle\" data-id=\"f84ed77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2601\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Reicht es, wenn ich ein Foto von meinem Kunstwerk (Gem\u00e4lde) schicke?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2601\"><p>Nein. Es wird tats\u00e4chlich das Original ben\u00f6tigt. Hintergrund ist, dass die Bilder in der \u00d6ffentlichkeit gezeigt werden und daf\u00fcr keine digitalen Reproduktionen genutzt werden sollen. Dies gilt ebenfalls f\u00fcr Fotografien. Au\u00dferdem m\u00fcssen die freigelassenen Ecken der Gem\u00e4lde noch bearbeitet werden. Das \u00fcbernehmen von uns ausgew\u00e4hlte K\u00fcnstlerInnen nach dem Erhalt der Kunstwerke.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e58bf elementor-widget elementor-widget-toggle\" data-id=\"e8e58bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2441\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2441\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist es m\u00f6glich, eine Ausnahme bei den vorgegebenen Aspekten der formalen Bildgestaltung (Leinwandgr\u00f6\u00dfe, Einteilung von bestimmten Bereichen der Leinwand) zu machen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2441\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2441\"><p>Nein. Das Konzept von \u201eSee the Big Picture\u201c erlaubt es nicht, von den vom Projekt gemachten Vorgaben f\u00fcr die formale Bildgestaltung abzuweichen. Diese sind unbedingt erforderlich, um die Idee von einem \u201eBig Picture\u201c, das aus vielen individuellen Bildern besteht, die ineinander \u00fcbergehen, verwirklichen zu k\u00f6nnen.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8a8e22 elementor-widget elementor-widget-toggle\" data-id=\"f8a8e22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2601\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche Daten\/Informationen werden \u00fcber mich erhoben und wo werden diese ver\u00f6ffentlicht?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2601\"><p>Auf der Projektwebsite (<a href=\"www.see-the-big-picture.com\">www.see-the-big-picture.com<\/a>) werden verschiedene Informationen \u00fcber die teilnehmenden K\u00fcnstlerinnen und K\u00fcnstler publiziert. Jegliche Informationen stammen ausschlie\u00dflich von den Kunstschaffenden selbst, d.h., dass sie entscheiden, was genau \u00fcber sie auf der Seite steht. Die Informationen dienen dazu, den Besucherinnen und Besuchern die M\u00f6glichkeit zu bieten, die Kunstschaffenden und ihre Arbeit besser kennenzulernen.<\/p>\n<p>Die K\u00fcnstlerinnen und K\u00fcnstlern werden gebeten, folgende Informationen selbst\u00e4ndig bereitzustellen:<\/p>\n<ul>\n<li>Biografie (in Bezug auf den k\u00fcnstlerischen Werdegang)<\/li>\n<li>Kontext zum eingereichten Bild (Entstehungsprozess, Motivation, Bedeutung, etc.)<\/li>\n<li>Portr\u00e4tfoto<\/li>\n<\/ul>\n<p>Sei dir bitte dar\u00fcber im Klaren, dass diese Informationen ggf. auch in der Berichterstattung von digitalen und Printmedien \u00fcber das Projekt ver\u00f6ffentlicht werden k\u00f6nnen. Durch Deine Teilnahme erkl\u00e4rst Du Dich hiermit einverstanden.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bad063 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bad063\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-453012a\" data-id=\"453012a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-553c1ac elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"553c1ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab3112b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab3112b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d971ba\" data-id=\"4d971ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb5e38c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cb5e38c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pen\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-884ff49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"884ff49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a38a779\" data-id=\"a38a779\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e12dff4 elementor-widget elementor-widget-heading\" data-id=\"e12dff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teilnahmebedingungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06ace43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06ace43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-837272d\" data-id=\"837272d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-983a963 elementor-widget elementor-widget-text-editor\" data-id=\"983a963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bevor wir Dich offiziell bei \u201eSee the Big Picture\u201c willkommen hei\u00dfen k\u00f6nnen, musst Du noch den Teilnahmebedingungen zustimmen. Zur Best\u00e4tigung Deines Einverst\u00e4ndnisses reicht eine Unterschrift am Ende des Dokuments. Bitte lies zuvor sorgf\u00e4ltig, welche Bedingungen darin gestellt werden. Wenn das erledigt ist, schicke das ausgef\u00fcllte Dokument bitte an: <a href=\"mailto:contact@see-the-big-picture.com\">contact@see-the-big-picture.com<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92be79e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92be79e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc888cf\" data-id=\"bc888cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b67a631 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"b67a631\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Terms-and-conditions-EN.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Teilnahmebedingungen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fef5e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fef5e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0fea8b\" data-id=\"b0fea8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66b52c6 elementor-widget elementor-widget-spacer\" data-id=\"66b52c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31d041c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31d041c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2d3c35\" data-id=\"c2d3c35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed6f3c1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ed6f3c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-box-open\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-723e637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"723e637\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32d6367\" data-id=\"32d6367\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df5dd04 elementor-widget elementor-widget-heading\" data-id=\"df5dd04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Versand<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66def4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66def4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fb5db4\" data-id=\"8fb5db4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1baf6c7 elementor-widget elementor-widget-text-editor\" data-id=\"1baf6c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Perfekt! Fast fertig. Jetzt kannst Du uns Dein Bild schicken.<strong>\u00a0<\/strong><\/p>\n<p><strong>Versandadresse f\u00fcr Kunstwerke<\/strong><\/p>\n<p>Desmond Doyle<\/p>\n<p>Art Mine<\/p>\n<p>Rossmarkt 6<\/p>\n<p>8793 Trofaiach<\/p>\n<p>\u00d6sterreich<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Teilnehmen Teile Deine Vision f\u00fcr eine gr\u00f6\u00dfere Perspektive See the Big Picture ist ein kollaboratives Kunstprojekt. Hier stehen Hobbykunstschaffende und professionelle K\u00fcnstlerinnen und K\u00fcnstler Seite an Seite, um mit ihrer Kunst eine Botschaft f\u00fcr mehr Zusammenhalt in der Welt zu verbreiten. Jeder individuelle Beitrag hat seine eigene Bedeutung und Aussage, im Vordergrund steht allerdings das [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5252,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"footnotes":""},"class_list":["post-7806","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>See the Big Picture - Teilnehmen<\/title>\n<meta name=\"description\" content=\"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"See the Big Picture - Teilnehmen\" \/>\n<meta property=\"og:description\" content=\"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"See the Big Picture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jointhebigpicture\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-17T05:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"See the Big Picture - Teilnehmen\" \/>\n<meta name=\"twitter:description\" content=\"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@jointhepicture\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/\",\"url\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/\",\"name\":\"See the Big Picture - Teilnehmen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/see-the-big-picture.com\\\/wp-content\\\/uploads\\\/Participate-4-Participate-2.jpg\",\"datePublished\":\"2021-06-17T05:47:01+00:00\",\"dateModified\":\"2021-06-17T05:47:02+00:00\",\"description\":\"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/see-the-big-picture.com\\\/wp-content\\\/uploads\\\/Participate-4-Participate-2.jpg\",\"contentUrl\":\"https:\\\/\\\/see-the-big-picture.com\\\/wp-content\\\/uploads\\\/Participate-4-Participate-2.jpg\",\"width\":1366,\"height\":768,\"caption\":\"test 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/teilnehmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/home-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teilnehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/\",\"name\":\"See the Big Picture\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/#organization\",\"name\":\"See the Big Picture\",\"url\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/see-the-big-picture.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/STBP_sym.png?fit=424%2C430&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/see-the-big-picture.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/STBP_sym.png?fit=424%2C430&ssl=1\",\"width\":424,\"height\":430,\"caption\":\"See the Big Picture\"},\"image\":{\"@id\":\"https:\\\/\\\/see-the-big-picture.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jointhebigpicture\\\/\",\"https:\\\/\\\/x.com\\\/jointhepicture\",\"https:\\\/\\\/www.instagram.com\\\/jointhebigpicture\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"See the Big Picture - Teilnehmen","description":"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/","og_locale":"de_DE","og_type":"article","og_title":"See the Big Picture - Teilnehmen","og_description":"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.","og_url":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/","og_site_name":"See the Big Picture","article_publisher":"https:\/\/www.facebook.com\/jointhebigpicture\/","article_modified_time":"2021-06-17T05:47:02+00:00","og_image":[{"url":"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"See the Big Picture - Teilnehmen","twitter_description":"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.","twitter_image":"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg","twitter_site":"@jointhepicture","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/","url":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/","name":"See the Big Picture - Teilnehmen","isPartOf":{"@id":"https:\/\/see-the-big-picture.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/#primaryimage"},"image":{"@id":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg","datePublished":"2021-06-17T05:47:01+00:00","dateModified":"2021-06-17T05:47:02+00:00","description":"Tritt See the Big Picture bei und werde Teil eines weltweiten Kollektivs von Maler*innen und Fotograf*innen, die ihre einzigartige Vision des Planeten teilen.","breadcrumb":{"@id":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/see-the-big-picture.com\/de\/teilnehmen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/#primaryimage","url":"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg","contentUrl":"https:\/\/see-the-big-picture.com\/wp-content\/uploads\/Participate-4-Participate-2.jpg","width":1366,"height":768,"caption":"test 2"},{"@type":"BreadcrumbList","@id":"https:\/\/see-the-big-picture.com\/de\/teilnehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/see-the-big-picture.com\/de\/home-2\/"},{"@type":"ListItem","position":2,"name":"Teilnehmen"}]},{"@type":"WebSite","@id":"https:\/\/see-the-big-picture.com\/de\/#website","url":"https:\/\/see-the-big-picture.com\/de\/","name":"See the Big Picture","description":"","publisher":{"@id":"https:\/\/see-the-big-picture.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/see-the-big-picture.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/see-the-big-picture.com\/de\/#organization","name":"See the Big Picture","url":"https:\/\/see-the-big-picture.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/see-the-big-picture.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/see-the-big-picture.com\/wp-content\/uploads\/2018\/06\/STBP_sym.png?fit=424%2C430&ssl=1","contentUrl":"https:\/\/i2.wp.com\/see-the-big-picture.com\/wp-content\/uploads\/2018\/06\/STBP_sym.png?fit=424%2C430&ssl=1","width":424,"height":430,"caption":"See the Big Picture"},"image":{"@id":"https:\/\/see-the-big-picture.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jointhebigpicture\/","https:\/\/x.com\/jointhepicture","https:\/\/www.instagram.com\/jointhebigpicture\/"]}]}},"campaignId":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/pages\/7806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/comments?post=7806"}],"version-history":[{"count":6,"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/pages\/7806\/revisions"}],"predecessor-version":[{"id":8685,"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/pages\/7806\/revisions\/8685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/media\/5252"}],"wp:attachment":[{"href":"https:\/\/see-the-big-picture.com\/de\/wp-json\/wp\/v2\/media?parent=7806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}